{"id":43488,"date":"2022-12-29T10:44:13","date_gmt":"2022-12-29T15:44:13","guid":{"rendered":"https:\/\/soretrostraps.com\/?post_type=product&#038;p=43488"},"modified":"2025-08-28T16:11:00","modified_gmt":"2025-08-28T20:11:00","slug":"alicante-aqua-exclusivo-bag-or-camera-strap","status":"publish","type":"product","link":"https:\/\/soretrostraps.com\/index.php\/product\/alicante-aqua-exclusivo-bag-or-camera-strap\/","title":{"rendered":"Alicante Aqua &#8211; Exclusivo &#8211; Bag or Camera Strap"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_592024278\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1353819370\">\n\n\t<div id=\"col-1871696122\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_326188462\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring.jpg 500w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-300x300.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_326188462 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2 class=\"uppercase\">Bags &amp; Purses<\/h2>\n<p>Our straps work great with any bag or purse that has rings. Bring new life to an old bag with a SoRetro Strap!<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1653098902\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_940568708\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-1024x1024.jpg 1024w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-600x599.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-300x300.jpg 300w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-768x767.jpg 768w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-247x247.jpg 247w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-400x400.jpg 400w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n.jpg 1080w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_940568708 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2 class=\"uppercase\">Cameras<\/h2>\n<p>A stylish and functional upgrade for any photographer&#8230;SoRetro Straps will literally change the way you feel about your camera!<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1344889304\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1470026862\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-300x300.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1470026862 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2 class=\"uppercase\">Whatever&#8230;<\/h2>\n<p>What you do with your strap is your business. If it has rings, it&#8217;ll probably work. We&#8217;ve used them on coolers, cases, controllers, and more.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_592024278 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 300px;\n  background-color: rgb(245, 245, 245);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-944927841\">\n\n\t<div id=\"col-2104234574\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 style=\"text-align: center;\"><span style=\"font-size: 200%;\">Yes&#8230;it will fit your camera!!<\/span><\/h2>\n<p style=\"text-align: center;\">We have yet to find a camera that doesn&#8217;t have a way to mount a SoRetro Strap to it.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-812286562\">\n\n\t<div id=\"col-5104169\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_559082554\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings.jpg\">\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-300x300.jpg 300w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-600x600.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-768x768.jpg 768w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_559082554 {\n  width: 65%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3><span style=\"font-size: 140%;\">Rings Included!<\/span><\/h3>\n<p>These heavy-duty triangular rings are included with every order and will give any camera a quick release mounting point.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2138525819\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1659954258\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts.jpg\">\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3 dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-300x300.jpg 300w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-600x600.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-768x768.jpg 768w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1659954258 {\n  width: 65%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3><span style=\"font-size: 140%;\">Slots or Nubbies?<\/span><\/h3>\n<p>Every camera we&#8217;ve encountered has either slides or nubbies (cause what else do you call them?). Your included rings will mount to these points.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_975356628\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1257645718\">\n\n\t<div id=\"col-307375874\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_703972432\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"344\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1.jpg 722w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-335x160.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-100x48.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-600x286.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-300x143.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_703972432 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1582614366\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"uppercase\"><span style=\"font-size: 150%;\">HandCrafted in Florida!<\/span><\/h2>\n<p>Please see the header at the top of our website for current processing dates to get an estimate on turn-around time.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_975356628 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<div class=\"su-table su-table-responsive\">\n<table>\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2776\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-ruler.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Adjustable 34&#8243; to 60&#8243;<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2778\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-crossbody.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Crossbody Length<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2774\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-leather.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Full Grain Leather<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2777 aligncenter\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-strong.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Super Strong Webbing<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2775\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-metal.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">All Metal Hardware<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><strong>*Some Exclusivos may be pictured\/shown with FYG leather ends that are not available for purchase.<\/strong><\/p>\n<p><strong>*We are allowing Backorders for Exclusivos for a limited time. Please be aware that backorders will be based on availability, processed in the order they&#8217;re received, and are not guaranteed. We will contact you if your backorder is not able to be processed.<\/strong><\/p>\n<p><span style=\"font-size: 80%;\">*Colors may vary slightly, due to the nature of the product.<\/span><\/p>\n","protected":false},"featured_media":43490,"template":"","meta":[],"product_brand":[],"product_cat":[135,356,368],"product_tag":[532,539,396,415,620,694,702,729,740,749,578,467,472,487,498,573],"giftcard-category":[],"class_list":{"0":"post-43488","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bag-and-camera-straps","7":"product_cat-exclusivo","8":"product_cat-exclusivo-2-0","9":"product_tag-background-seethrough-natural","10":"product_tag-finish-metallic-accents","11":"product_tag-main-blue","12":"product_tag-main-hot-pink","13":"product_tag-maker-kmm-malibu","14":"product_tag-maker-plg-crush","15":"product_tag-maker-plg-eucalyptus","16":"product_tag-maker-plg-peacock","17":"product_tag-maker-plg-satsuma","18":"product_tag-maker-plg-tangerine","19":"product_tag-secondary-cream","20":"product_tag-secondary-green","21":"product_tag-secondary-light-blue","22":"product_tag-secondary-orange","23":"product_tag-secondary-teal","24":"product_tag-theme-floral","25":"product_shipping_class-usps-first-class-package","27":"first","28":"outofstock","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-variable","33":"has-default-attributes"},"gallery_images":[],"_links":{"self":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product\/43488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/media\/43490"}],"wp:attachment":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/media?parent=43488"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=43488"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=43488"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=43488"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/giftcard-category?post=43488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}