{"id":37920,"date":"2022-06-19T20:37:14","date_gmt":"2022-06-20T00:37:14","guid":{"rendered":"https:\/\/soretrostraps.com\/?post_type=product&#038;p=37920"},"modified":"2022-08-01T14:31:43","modified_gmt":"2022-08-01T18:31:43","slug":"exclusivo-santa-maria-bag-or-camera-strap-perfectly-imperfect-shorty","status":"publish","type":"product","link":"https:\/\/soretrostraps.com\/index.php\/product\/exclusivo-santa-maria-bag-or-camera-strap-perfectly-imperfect-shorty\/","title":{"rendered":"Exclusivo &#8211; Santa Maria &#8211; Bag or Camera Strap &#8211; Perfectly Imperfect Shorty"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_1439043464\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1281510849\">\n\n\t<div id=\"col-1201692918\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1653285139\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring.jpg 500w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Bag-Ring-300x300.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1653285139 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2 class=\"uppercase\">Bags &amp; Purses<\/h2>\n<p>Our straps work great with any bag or purse that has rings. Bring new life to an old bag with a SoRetro Strap!<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-317795452\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2121621023\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-1024x1024.jpg 1024w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-600x599.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-300x300.jpg 300w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-768x767.jpg 768w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-247x247.jpg 247w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n-400x400.jpg 400w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2018\/10\/43133314_145954653027093_1647404799848787132_n.jpg 1080w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2121621023 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2 class=\"uppercase\">Cameras<\/h2>\n<p>A stylish and functional upgrade for any photographer&#8230;SoRetro Straps will literally change the way you feel about your camera!<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1515322199\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1039750964\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Alicia-Bag-300x300.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1039750964 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2 class=\"uppercase\">Whatever&#8230;<\/h2>\n<p>What you do with your strap is your business. If it has rings, it&#8217;ll probably work. We&#8217;ve used them on coolers, cases, controllers, and more.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1439043464 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 300px;\n  background-color: rgb(245, 245, 245);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1513277402\">\n\n\t<div id=\"col-1358073645\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 style=\"text-align: center;\"><span style=\"font-size: 200%;\">Yes&#8230;it will fit your camera!!<\/span><\/h2>\n<p style=\"text-align: center;\">We have yet to find a camera that doesn&#8217;t have a way to mount a SoRetro Strap to it.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-610060891\">\n\n\t<div id=\"col-1001979499\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1503642497\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings.jpg\">\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-300x300.jpg 300w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-600x600.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings-768x768.jpg 768w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Rings.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1503642497 {\n  width: 65%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3><span style=\"font-size: 140%;\">Rings Included!<\/span><\/h3>\n<p>These heavy-duty triangular rings are included with every order and will give any camera a quick release mounting point.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1426179616\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1185664799\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts.jpg\">\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-3 dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-300x300.jpg 300w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-335x335.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-100x100.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-600x600.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-150x150.jpg 150w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts-768x768.jpg 768w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Camera-Mounts.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1185664799 {\n  width: 65%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3><span style=\"font-size: 140%;\">Slots or Nubbies?<\/span><\/h3>\n<p>Every camera we&#8217;ve encountered has either slides or nubbies (cause what else do you call them?). Your included rings will mount to these points.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_462256261\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-2031995010\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2031995010 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-2120657059\">\n\n\t<div id=\"col-525697960\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgba(255, 255, 255, 0);\" >\n\t\t\t\n\t\t\t\n<h2><span style=\"font-size: 160%;\">Want to make your own custom strap??<\/span><\/h2>\n<p class=\"thin-font\"><span style=\"font-size: 160%;\">Try our strap builder and build the strap of your dreams!<\/span><\/p>\n<a href=\"https:\/\/soretrostraps.com\/index.php\/product\/custom-soretro-strap\/\" class=\"button primary is-gloss is-xlarge box-shadow-2 box-shadow-4-hover expand\" style=\"border-radius:12px;\">\n\t\t<span>Strap Builder<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1064945724\" class=\"col medium-6 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1326377655\">\n\t\t<a class=\"\" href=\"https:\/\/soretrostraps.com\/index.php\/product\/custom-soretro-strap\/\" >\t\t\t\t\t\t<div class=\"img-inner image-zoom box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Customizer-Graphic-Small.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Customizer-Graphic-Small.jpg 513w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Customizer-Graphic-Small-335x225.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Customizer-Graphic-Small-100x67.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Customizer-Graphic-Small-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1326377655 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-2120657059 > .col > .col-inner {\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-1060667656\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1060667656 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_462256261 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  min-height: 300px;\n  background-color: rgb(245, 245, 245);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_527522002\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-81680096\">\n\n\t<div id=\"col-1609287516\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1750469859\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"344\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1.jpg 722w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-335x160.jpg 335w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-100x48.jpg 100w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-600x286.jpg 600w, https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/Russell-1-300x143.jpg 300w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1750469859 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-921267004\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"uppercase\"><span style=\"font-size: 150%;\">HandCrafted in Florida &amp; Michigan!<\/span><\/h2>\n<p>Please see the header at the top of our website for current processing dates to get an estimate on turn-around time.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_527522002 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<div class=\"su-table su-table-responsive\">\n<table>\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2776\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-ruler.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Adjustable Shorty<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2778\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-crossbody.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Crossbody Length<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2774\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-leather.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Full Grain Leather<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2777 aligncenter\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-strong.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">Super Strong Webbing<\/span><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2775\" src=\"https:\/\/soretrostraps.com\/wp-content\/uploads\/2019\/10\/icon-metal.gif\" alt=\"\" width=\"40\" height=\"40\" \/><\/td>\n<td><span style=\"font-size: 120%\">All Metal Hardware<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><span style=\"font-size: 80%;\">*Leather colors may vary slightly, due to the nature of the product.<\/span><\/p>\n","protected":false},"featured_media":37838,"template":"","meta":[],"product_brand":[],"product_cat":[356],"product_tag":[532,407,409,413,415,424,433,434,447,573],"giftcard-category":[],"class_list":{"0":"post-37920","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-exclusivo","7":"product_tag-background-seethrough-natural","8":"product_tag-main-coral","9":"product_tag-main-dark-green","10":"product_tag-main-green","11":"product_tag-main-hot-pink","12":"product_tag-main-marigold","13":"product_tag-main-pale-pink","14":"product_tag-main-pine","15":"product_tag-main-yellow","16":"product_tag-theme-floral","17":"product_shipping_class-usps-first-class-package","19":"first","20":"outofstock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"gallery_images":[],"_links":{"self":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product\/37920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/media\/37838"}],"wp:attachment":[{"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/media?parent=37920"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=37920"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=37920"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=37920"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/soretrostraps.com\/index.php\/wp-json\/wp\/v2\/giftcard-category?post=37920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}